{"id":3486,"count":6,"description":"","link":"https:\/\/lacantinettaweb.com\/es\/categoria-prodotto\/region\/otras-regiones\/tokaji\/","name":"Tokaji","slug":"tokaji","taxonomy":"product_cat","parent":3427,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tokaji Archivi - La Cantinetta Web<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lacantinettaweb.com\/es\/categoria-prodotto\/region\/otras-regiones\/tokaji\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tokaji Archivi - La Cantinetta Web\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lacantinettaweb.com\/es\/categoria-prodotto\/region\/otras-regiones\/tokaji\/\" \/>\n<meta property=\"og:site_name\" content=\"La Cantinetta Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lacantinettaweb.com\\\/es\\\/categoria-prodotto\\\/region\\\/otras-regiones\\\/tokaji\\\/\",\"url\":\"https:\\\/\\\/lacantinettaweb.com\\\/es\\\/categoria-prodotto\\\/region\\\/otras-regiones\\\/tokaji\\\/\",\"name\":\"Tokaji Archivi - La Cantinetta Web\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lacantinettaweb.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lacantinettaweb.com\\\/es\\\/categoria-prodotto\\\/region\\\/otras-regiones\\\/tokaji\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lacantinettaweb.com\\\/es\\\/categoria-prodotto\\\/region\\\/otras-regiones\\\/tokaji\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lacantinettaweb.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Regi\u00f3n\",\"item\":\"https:\\\/\\\/lacantinettaweb.com\\\/es\\\/categoria-prodotto\\\/region\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Otras regiones\",\"item\":\"https:\\\/\\\/lacantinettaweb.com\\\/es\\\/categoria-prodotto\\\/region\\\/otras-regiones\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Tokaji\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lacantinettaweb.com\\\/#website\",\"url\":\"https:\\\/\\\/lacantinettaweb.com\\\/\",\"name\":\"La Cantinetta Web\",\"description\":\"Enoteca Online di Vini e Box Degustazione\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lacantinettaweb.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tokaji Archivi - La Cantinetta Web","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lacantinettaweb.com\/es\/categoria-prodotto\/region\/otras-regiones\/tokaji\/","og_locale":"es_ES","og_type":"article","og_title":"Tokaji Archivi - La Cantinetta Web","og_url":"https:\/\/lacantinettaweb.com\/es\/categoria-prodotto\/region\/otras-regiones\/tokaji\/","og_site_name":"La Cantinetta Web","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lacantinettaweb.com\/es\/categoria-prodotto\/region\/otras-regiones\/tokaji\/","url":"https:\/\/lacantinettaweb.com\/es\/categoria-prodotto\/region\/otras-regiones\/tokaji\/","name":"Tokaji Archivi - La Cantinetta Web","isPartOf":{"@id":"https:\/\/lacantinettaweb.com\/#website"},"breadcrumb":{"@id":"https:\/\/lacantinettaweb.com\/es\/categoria-prodotto\/region\/otras-regiones\/tokaji\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/lacantinettaweb.com\/es\/categoria-prodotto\/region\/otras-regiones\/tokaji\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lacantinettaweb.com\/es\/"},{"@type":"ListItem","position":2,"name":"Regi\u00f3n","item":"https:\/\/lacantinettaweb.com\/es\/categoria-prodotto\/region\/"},{"@type":"ListItem","position":3,"name":"Otras regiones","item":"https:\/\/lacantinettaweb.com\/es\/categoria-prodotto\/region\/otras-regiones\/"},{"@type":"ListItem","position":4,"name":"Tokaji"}]},{"@type":"WebSite","@id":"https:\/\/lacantinettaweb.com\/#website","url":"https:\/\/lacantinettaweb.com\/","name":"La Cantinetta Web","description":"Enoteca Online di Vini e Box Degustazione","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lacantinettaweb.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/lacantinettaweb.com\/es\/wp-json\/wp\/v2\/product_cat\/3486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacantinettaweb.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/lacantinettaweb.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/lacantinettaweb.com\/es\/wp-json\/wp\/v2\/product_cat\/3427"}],"wp:post_type":[{"href":"https:\/\/lacantinettaweb.com\/es\/wp-json\/wp\/v2\/product?product_cat=3486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}